
    {"id":16957,"date":"2023-06-14T16:10:44","date_gmt":"2023-06-14T14:10:44","guid":{"rendered":"\/?p=16957"},"modified":"2025-05-30T12:48:43","modified_gmt":"2025-05-30T10:48:43","slug":"arbeitshosen-baumwolle-oder-mischmateriallien","status":"publish","type":"post","link":"https:\/\/lindstromgroup.com\/at\/article\/arbeitshosen-baumwolle-oder-mischmateriallien\/","title":{"rendered":"Arbeitshosen aus Baumwolle sind schon lange nicht mehr in!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Viele Menschen glauben noch immer, dass Arbeitshosen nur aus Baumwolle und in blauer Farbe hergestellt werden. Das h\u00e4ngt mit der Vorstellung zusammen, dass Baumwolle weich, bequem und leicht zu pflegen ist und dass alles was k\u00fcnstlich ist kratzt, juckt, stinkt und nicht gut gereinigt werden kann. Diese Annahmen sind heute nicht mehr so ganz wahr und die Funktionalit\u00e4t und \u00c4sthetik der Arbeitskleidung aus gemischten Materialien wird Sie sicherlich \u00fcberraschen.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"456\" height=\"512\" src=\"https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/35\/2024\/06\/lindstrom-bavlnene-pracovni-kalhoty-uz-davno-nejsou-in-062023-2.png\" alt=\"\" class=\"wp-image-17315\" srcset=\"https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/35\/2024\/06\/lindstrom-bavlnene-pracovni-kalhoty-uz-davno-nejsou-in-062023-2.png 456w, https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/35\/2024\/06\/lindstrom-bavlnene-pracovni-kalhoty-uz-davno-nejsou-in-062023-2-267x300.png 267w\" sizes=\"(max-width: 456px) 100vw, 456px\" \/><figcaption class=\"wp-element-caption\"><em>Funktionelle und gut sitzende Arbeitskleidung<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Materialien f\u00fcr Arbeitskleidung<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Gegenw\u00e4rtig wird Arbeitskleidung aus verschiedenen Materialien hergestellt und der Kunde kann es gem\u00e4\u00df den Eigenschaften aussuchen, die er ben\u00f6tigt. Arbeitshosen werden in den meisten F\u00e4llen aus gemischten Materialien hergestellt, wobei in einem unterschiedlichen Verh\u00e4ltnis Polyester und Baumwolle vertreten ist oder diese aus reiner Baumwolle hergestellt werden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Traditionelle Baumwolle<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Klassische Arbeitshosen aus 100% Baumwolle sind immer noch, dank ihrer bew\u00e4hrten Eigenschaften beliebt und viele M\u00e4nner k\u00f6nnen sich keine andere Arbeitshose vorstellen. Baumwolle ist ein angenehmes nat\u00fcrliches Material, das fest und saugf\u00e4hig ist. Viele M\u00e4nner lieben deshalb ihre alten verwaschenen oder ausgedehnten T-Shirts und ihre <strong>blauen Baumwollarbeitshosen<\/strong>, bei denen sie bei der Arbeit keine Angst haben m\u00fcssen, dass sie schmutzig werden. Aus Baumwolle werden Arbeitshosen mit klassischen Schnitten hergestellt, die Handwerker und Heimwerker schon vor vielen Jahrzehnten getragen haben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Viele erinnern sich sicherlich noch an die unangenehmen Dinge und sind sich der Unzul\u00e4nglichkeiten bewusst, auf die sie bei dieser Arbeitskleidung gesto\u00dfen sind und immer noch sto\u00dfen. Nach mehreren Waschg\u00e4ngen wird Kleidung aus Baumwolle kleiner, also haben die <strong>Arbeitshosen <\/strong>um einige Zentimeter k\u00fcrzere Hosenbeine. Die Farben bleichen aus und jeder erkennt auf den ersten Blick, dass die Arbeitshose sch\u00f6n etwas erlebt hat. Die starke Baumwolle knittert viel und l\u00e4sst sich nicht ordentlich b\u00fcgeln. Der Handwerker sieht sicherlich nicht wie aus dem Katalog aus, was bei Kunden Zweifel \u00fcber die Qualit\u00e4t Ihrer Firma aufkommen lassen kann.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Moderne Mischmaterialien<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Modernen jungen M\u00e4nnern und Frauen, die auch bei der manuellen Arbeit gut aussehen wollen, bieten wir <strong>Arbeitskleidung aus Mischmaterialien<\/strong> (Polyester, Baumwolle und weiteren Fasern) an, die hervorragende Eigenschaften haben, komfortabel und gut zu reinigen sind.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die universellste Gruppe der Materialien, die f\u00fcr Arbeitskleidung verwendet wird ist die Mischung PES\/CO (65 % Polyesterfasern und 35 % Baumwolle). Gegen\u00fcber Kleidung aus reiner Baumwolle hat dieses Material einige unstrittige Vorteile:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Erhaltung der Farben auch nach mehrfacher industrieller Reinigung,<\/li>\n\n\n\n<li>beh\u00e4lt seine Gr\u00f6\u00dfe,<\/li>\n\n\n\n<li>zerknittert nicht, franst zum Beispiel an den Manschetten und N\u00e4hten nicht aus.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Die Firma Lindstr\u00f6m testest die Materialien unter extremen Belastungen. Das bedeutet, dass die Kleidung aus diesen Materialien lange h\u00e4lt und ihr Preis im Endeffekt g\u00fcnstiger ist, d.b. dass diese wirtschaftlich und auch umweltfreundlich ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die wirtschaftlicheren Varianten haben noch einen geringeren Baumwollanteil. <strong>Mischfasern mit einem h\u00f6heren Baumwollanteil<\/strong> werden f\u00fcr die Arbeitskleidung der Verbrauchs- und Backindustrie verwendet, sie erf\u00fcllen ihren Zweck jedoch auch sehr gut in der Gastronomie und im Hotelwesen, im medizinischen Bereich oder auch beim Rettungsdienst. Dank der beigef\u00fcgten Baumwolle handelt es sich um ein perfektes Material f\u00fcr Sommerkleidung.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Gewebe f\u00fcr Risikoumgebungen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Einige Arbeitsumgebungen sind gef\u00e4hrlicher und es drohen spezielle Risiken. Arbeitskleidung aus speziellem Gewebe kann Unfallfolgen mindern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Antistatisches Gewebe<\/strong> ist f\u00fcr die Arbeitskleidung der Mitarbeiter der Elektro-, Treibstoff- und Gasindustrie bestimmt und wird \u00fcberall dort verwendet, wo w\u00e4hrend der Arbeit ein Schutz vor Einfl\u00fcssen durch die elektrische Leitf\u00e4higkeit wichtig ist. Sie wird in einem unterschiedlichen Verh\u00e4ltnis aus Baumwolle und Polyester so hergestellt, damit sie dem gegebenen Zweck am besten entspricht.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"114\" height=\"171\" src=\"https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/35\/2024\/06\/pasted-image-0-1.png\" alt=\"\" class=\"wp-image-17316\"\/><figcaption class=\"wp-element-caption\">Spezielle Arbeitskleidung f\u00fcr Risikoumfelder<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"114\" height=\"171\" src=\"https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/35\/2024\/06\/pasted-image-0-2.png\" alt=\"\" class=\"wp-image-17318\"\/><figcaption class=\"wp-element-caption\">Spezielle Arbeitskleidung f\u00fcr Risikoumfelder<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"128\" height=\"171\" src=\"https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/35\/2024\/06\/pasted-image-0-3.png\" alt=\"\" class=\"wp-image-17319\"\/><figcaption class=\"wp-element-caption\">Spezielle Arbeitskleidung f\u00fcr Risikoumfelder<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"125\" height=\"171\" src=\"https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/35\/2024\/06\/unnamed-1.png\" alt=\"\" class=\"wp-image-17320\"\/><figcaption class=\"wp-element-caption\">Spezielle Arbeitskleidung f\u00fcr Risikoumfelder<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hydrophobes Gewebe<\/strong> wird nachtr\u00e4glich so behandelt, damit es Wasser abweist, wasserfest (hydrophob) ist und je nach Verwendungszweck kann dieses Gewebe auch luftdurchl\u00e4ssig sein. Daf\u00fcr kann auf verschiedene Arten gesorgt werden \u2013 entweder durch eine Paste, eine aufgeklebte Folie oder die modernste Art der Laminierung (Aufkleben einer speziellen Membran).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gewebe f\u00fcr spezielle Zwecke<\/strong> ist f\u00fcr die Kleidung von Sicherheitsdiensten, Wachdiensten, f\u00fcr Personen die mit Feuer oder statischer Elektrizit\u00e4t in Kontakt kommen bestimmt. Die Zusammensetzung und die weiche Verarbeitung sorgen f\u00fcr ein elegantes Aussehen. Die spezielle Behandlung sorgt f\u00fcr lang anhaltende Farbigkeit und eine sehr gute Widerstandsf\u00e4higkeit, die auch die strengsten Kriterien erf\u00fcllt.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"501\" height=\"668\" src=\"https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/35\/2024\/06\/lindstrom-bavlnene-pracovni-kalhoty-uz-davno-nejsou-in-062023-3.jpg\" alt=\"\" class=\"wp-image-17321\" srcset=\"https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/35\/2024\/06\/lindstrom-bavlnene-pracovni-kalhoty-uz-davno-nejsou-in-062023-3.jpg 501w, https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/35\/2024\/06\/lindstrom-bavlnene-pracovni-kalhoty-uz-davno-nejsou-in-062023-3-225x300.jpg 225w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><figcaption class=\"wp-element-caption\"><em>Arbeitskleidung mit der jeweiligen Kennzeichnung<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Arbeitshosen mit erstklassigen Eigenschaften die auch gut aussehen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Arbeitskleidung kann auch sehr gut aussehen. Die Kollektionen, die Funktionalit\u00e4t und ausgezeichnetes Design verbinden zeichnen sich durch kleine Details, wie <a href=\"https:\/\/lindstromgroup.com\/at\/mietservice\/arbeitskleidung\/arbeitskleidung-mit-hoher-sichtbarkeit\/\">reflektierende Elemente<\/a> und dekorative Muster aus. Durch ihren ergonomischen Schnitt entsprechen sie den h\u00f6chsten Standards der Firmenrepr\u00e4sentation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Die Mischung mit einem h\u00f6heren Anteil an Baumwolle (62 %), Polyester (35 %) und elastischen Spandex Fasern<\/strong> hebt die ausgezeichneten Eigenschaften der Baumwolle hervor \u2013 angenehm zum Anfassen, atmungsaktiv und ausgezeichnete Saugf\u00e4higkeit. Dank dem Polyester steigt wiederum die Festigkeit, das Material schrumpft und zerknittert nicht so stark, die Kleidung ist formstabil und widerstandsf\u00e4higer gegen Verschmutzungen, wodurch die Lebensdauer bei h\u00e4ufiger W\u00e4sche verl\u00e4ngert wird. Die letzte Beimengung, die elastische Spandex Faser, verleiht dem Material noch weitere Eigenschaften \u2013 es l\u00e4sst sich dehnen und kehrt, dank seinem Formged\u00e4chtnis, in seine urspr\u00fcngliche Form zur\u00fcck.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Materialien, die in unserer Firma Lindstr\u00f6m verwendet werden<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Materialien, aus denen die <a href=\"https:\/\/lindstromgroup.com\/at\/mietservice\/arbeitskleidung\/\">von unserer Firma angebotene Arbeitskleidung hergestellt wird<\/a>, tragen eine genaue Kennzeichnung mit Angabe des Fl\u00e4chengewichtes und des Anteiles der einzelnen Bestandteile. Wir f\u00fchren hier einige Beispiele an:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PRO TWILL 245 65\/35 PES\/CO<\/strong> \u2013 das g\u00e4ngigste Material, das f\u00fcr Arbeitshosen, M\u00e4ntel, Westen, Blusen und Overalls verwendet wird<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PRO TWILL 210 65\/35 PES\/CO<\/strong> \u2013 ein leichteres Material, das f\u00fcr die Lebensmittelindustrie, das Gesundheitswesen u.\u00c4., oder f\u00fcr die Sommermodelle der Arbeitskleidung (Hosen, M\u00e4ntel, Westen) verwendet wird<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PRO OUTDOOR 230 70\/30 PES\/CO<\/strong> \u2013 Material f\u00fcr Oberbekleidung (Jacken, Hosen, Winterjacken, reflektierende Kleidung)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PIQUE KNIT 190 65\/35 PES\/CO<\/strong> \u2013 Arbeits-T-Shirts<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>WELDING FR CL2 420 80\/20 CO\/PES<\/strong> \u2013 feuerfestes Material f\u00fcr Schwei\u00dfer<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FLEECE 250 100 PES <\/strong>\u2013 Fleecejacken und Fleecewesten<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>BAKER 210 100 CO<\/strong> \u2013 T-Shirts f\u00fcr B\u00e4cker<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Textilallergien \u2013 wie diese vermieden werden k\u00f6nnen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Allergische Reaktionen auf Textilien sind eher selten und in Wirklichkeit sehr ungew\u00f6hnlich. Die Gr\u00fcnde f\u00fcr gereizte Haut liegen oft woanders:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>neues, ungewaschenes Material und N\u00e4hte,<\/li>\n\n\n\n<li>zu enge Kleidung (die richtige Gr\u00f6\u00dfe ist wichtig),<\/li>\n\n\n\n<li>Logos und Etiketten an der Kleidung,<\/li>\n\n\n\n<li>Metallkn\u00f6pfe, Rei\u00dfverschl\u00fcsse usw. im direkten Kontakt mit der Haut,<\/li>\n\n\n\n<li>F\u00e4den und N\u00e4hte, die die Haut reizen,<\/li>\n\n\n\n<li>schlecht gesp\u00fclte Kleidung \u2013 Waschmittelreste.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Unsere Firma arbeitet mit zuverl\u00e4ssigen Lieferanten von Materialien zusammen, die auf der Basis von Baumwollgemischen hergestellt werden. Oft sind ihre Produkte mit dem Zertifikat OEKO-TEX\u00ae Standard 100 gekennzeichnet, was ein unabh\u00e4ngiges Test- und Zertifizierungssystem f\u00fcr Textilrohstoffe, Zwischenprodukte und Endprodukte in allen Phasen der Produktion ist. Damit wir das Risiko von allergischen Hautreaktionen minimieren, werden die Textilien von uns gr\u00fcndlich getestet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Der Test auf sch\u00e4dliche Stoffe<\/strong> umfasst: illegale Stoffe, gesetzlich regulierte Stoffe, bekannte sch\u00e4dliche (nicht jedoch durch das Gesetz regulierte) Chemikalien, ebenso wie die Parameter der Gesundheitspflege. Die Anforderungen \u00fcbersteigen die bestehenden innerstaatlichen Rechtsvorschriften im gesamten Umfang. Der sorgf\u00e4ltig \u00fcberwachte Waschzyklus garantiert, dass keine Waschmittelreste in den Textilien bleiben.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Lindstr\u00f6m EN zertifizierte Arbeitskleidung<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Unsere Arbeitskleidung wird gem\u00e4\u00df den strengen europ\u00e4ischen Normen hergestellt und tr\u00e4gt die erforderliche Kennzeichnung. Die Richtlinie 89\/686\/EWG wurde von der Europ\u00e4ischen Union mit dem Ziel herausgegeben um in der gesamten Europ\u00e4ischen Union f\u00fcr gleich sichere Produkte zu sorgen. Wir bieten Arbeitskleidung f\u00fcr verschiedene Branchen mit spezifischen Eigenschaften und der erforderlichen Kennzeichnung an. Die<strong> Arbeitsschutzkleidung<\/strong> erf\u00fcllt die Anforderungen der Norm <strong>EN ISO 13688<\/strong>. Diese Norm wird kombiniert mit einer weiteren Norm angewandt, die die Anforderungen an die spezifische Ausf\u00fchrung von Produkten, die einen Schutz bieten enth\u00e4lt, z.B.:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"810\" height=\"450\" src=\"https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/35\/2024\/06\/GE_CTA_buttton_WWS_automotive.jpg\" alt=\"\" class=\"wp-image-17304\" srcset=\"https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/35\/2024\/06\/GE_CTA_buttton_WWS_automotive.jpg 810w, https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/35\/2024\/06\/GE_CTA_buttton_WWS_automotive-300x167.jpg 300w, https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/35\/2024\/06\/GE_CTA_buttton_WWS_automotive-768x427.jpg 768w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"30\" height=\"35\" src=\"https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/35\/2024\/06\/lindstrom-en-normy-062023-1.jpg\" alt=\"\" class=\"wp-image-17322\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>EN 11611<\/strong><br>Schutz beim Schwei\u00dfen und verwandten Verfahren<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"30\" height=\"35\" src=\"https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/35\/2024\/06\/lindstrom-en-normy-062023-2.jpg\" alt=\"\" class=\"wp-image-17323\" style=\"height:35px\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>EN 381<\/strong><br>Schutzkleidung f\u00fcr die Benutzer von handgef\u00fchrten Kettens\u00e4gen<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"118\" height=\"107\" src=\"https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/35\/2024\/06\/lindstrom-en-normy-062023-3.jpg\" alt=\"\" class=\"wp-image-17324\" style=\"width:auto;height:35px\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>EN 342<\/strong><br>Schutz vor K\u00e4lte<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"52\" height=\"58\" src=\"https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/35\/2024\/06\/lindstrom-en-normy-062023-4.jpg\" alt=\"\" class=\"wp-image-17325\" style=\"width:auto;height:35px\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>EN 533<\/strong><br>Schutz vor Hitze und Feuer<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"30\" height=\"35\" src=\"https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/35\/2024\/06\/lindstrom-en-normy-062023-5.jpg\" alt=\"\" class=\"wp-image-17326\" style=\"width:auto;height:35px\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>EN 343<\/strong><br>Schutz vor Regen<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unser Ziel ist es die optimalste L\u00f6sung f\u00fcr die Arbeitskleidung jedes Kunden zu finden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viele Menschen glauben noch immer, dass Arbeitshosen nur aus Baumwolle und in blauer Farbe hergestellt werden. Das h\u00e4ngt mit der Vorstellung zusammen, dass Baumwolle weich,&#8230;<\/p>\n","protected":false},"author":14,"featured_media":16958,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_eb_attr":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[14],"tags":[39,57,44],"coauthors":[20],"class_list":["post-16957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","tag-arbeitskleidung","tag-qualitaetsmanagement","tag-sicherheit"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Arbeitshosen aus Baumwolle sind nicht mehr in! - Lindstr\u00f6m<\/title>\n<meta name=\"description\" content=\"Viele glauben immer noch, dass Arbeitshosen aus Baumwolle hergestellt werden und blau sein m\u00fcssen. Die Funktionalit\u00e4t und \u00c4sthetik der Mischmateriallien ist jedoch \u00fcberraschend.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arbeitshosen aus Baumwolle sind schon lange nicht mehr in!\" \/>\n<meta property=\"og:description\" content=\"Viele glauben immer noch, dass Arbeitshosen aus Baumwolle hergestellt werden und blau sein m\u00fcssen. Die Funktionalit\u00e4t und \u00c4sthetik der Mischmateriallien ist jedoch \u00fcberraschend.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lindstromgroup.com\/at\/article\/arbeitshosen-baumwolle-oder-mischmateriallien\/\" \/>\n<meta property=\"og:site_name\" content=\"Lindstr\u00f6m Austria\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-14T14:10:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-30T10:48:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lindstrom-sites.s3.eu-north-1.amazonaws.com\/wp-content\/uploads\/sites\/26\/2024\/05\/lindstrom-arbeitshosen-baumwolle-oder-mischmateriallien-052024-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lindstr\u00f6m Group\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lindstr\u00f6m Group\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Lindstr\u00f6m Group\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/article\\\/arbeitshosen-baumwolle-oder-mischmateriallien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/article\\\/arbeitshosen-baumwolle-oder-mischmateriallien\\\/\"},\"author\":{\"name\":\"Lindstr\u00f6m Group\",\"@id\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/#\\\/schema\\\/person\\\/9111900e3f15be99cf4a104112bf0bc3\"},\"headline\":\"Arbeitshosen aus Baumwolle sind schon lange nicht mehr in!\",\"datePublished\":\"2023-06-14T14:10:44+00:00\",\"dateModified\":\"2025-05-30T10:48:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/article\\\/arbeitshosen-baumwolle-oder-mischmateriallien\\\/\"},\"wordCount\":1356,\"publisher\":{\"@id\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/article\\\/arbeitshosen-baumwolle-oder-mischmateriallien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d2ris6qfzcz0wn.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2024\\\/05\\\/lindstrom-arbeitshosen-baumwolle-oder-mischmateriallien-052024-1.jpg\",\"keywords\":[\"#arbeitskleidung\",\"#qualit\u00e4tsmanagement\",\"#sicherheit\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"de-AT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/article\\\/arbeitshosen-baumwolle-oder-mischmateriallien\\\/\",\"url\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/article\\\/arbeitshosen-baumwolle-oder-mischmateriallien\\\/\",\"name\":\"Arbeitshosen aus Baumwolle sind nicht mehr in! - Lindstr\u00f6m\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/article\\\/arbeitshosen-baumwolle-oder-mischmateriallien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/article\\\/arbeitshosen-baumwolle-oder-mischmateriallien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d2ris6qfzcz0wn.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2024\\\/05\\\/lindstrom-arbeitshosen-baumwolle-oder-mischmateriallien-052024-1.jpg\",\"datePublished\":\"2023-06-14T14:10:44+00:00\",\"dateModified\":\"2025-05-30T10:48:43+00:00\",\"description\":\"Viele glauben immer noch, dass Arbeitshosen aus Baumwolle hergestellt werden und blau sein m\u00fcssen. Die Funktionalit\u00e4t und \u00c4sthetik der Mischmateriallien ist jedoch \u00fcberraschend.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/article\\\/arbeitshosen-baumwolle-oder-mischmateriallien\\\/#breadcrumb\"},\"inLanguage\":\"de-AT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/article\\\/arbeitshosen-baumwolle-oder-mischmateriallien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-AT\",\"@id\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/article\\\/arbeitshosen-baumwolle-oder-mischmateriallien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d2ris6qfzcz0wn.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2024\\\/05\\\/lindstrom-arbeitshosen-baumwolle-oder-mischmateriallien-052024-1.jpg\",\"contentUrl\":\"https:\\\/\\\/d2ris6qfzcz0wn.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2024\\\/05\\\/lindstrom-arbeitshosen-baumwolle-oder-mischmateriallien-052024-1.jpg\",\"width\":1024,\"height\":682},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/article\\\/arbeitshosen-baumwolle-oder-mischmateriallien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/category\\\/article\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Arbeitshosen aus Baumwolle sind schon lange nicht mehr in!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/#website\",\"url\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/\",\"name\":\"Lindstr\u00f6m Austria\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-AT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/#organization\",\"name\":\"Lindstr\u00f6m Austria\",\"url\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-AT\",\"@id\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d2ris6qfzcz0wn.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2023\\\/10\\\/Logo512.png\",\"contentUrl\":\"https:\\\/\\\/d2ris6qfzcz0wn.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2023\\\/10\\\/Logo512.png\",\"width\":512,\"height\":109,\"caption\":\"Lindstr\u00f6m Austria\"},\"image\":{\"@id\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lindstromgroup.com\\\/at\\\/#\\\/schema\\\/person\\\/9111900e3f15be99cf4a104112bf0bc3\",\"name\":\"Lindstr\u00f6m Group\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-AT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/db72e9a46e0f7c5c437401114209c070c0ed0871f3f73ed82792b5cf14c95b5c?s=96&d=mm&r=g93dbf206f3a4403aba72a0da0a795367\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/db72e9a46e0f7c5c437401114209c070c0ed0871f3f73ed82792b5cf14c95b5c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/db72e9a46e0f7c5c437401114209c070c0ed0871f3f73ed82792b5cf14c95b5c?s=96&d=mm&r=g\",\"caption\":\"Lindstr\u00f6m Group\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Arbeitshosen aus Baumwolle sind nicht mehr in! - Lindstr\u00f6m","description":"Viele glauben immer noch, dass Arbeitshosen aus Baumwolle hergestellt werden und blau sein m\u00fcssen. Die Funktionalit\u00e4t und \u00c4sthetik der Mischmateriallien ist jedoch \u00fcberraschend.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Arbeitshosen aus Baumwolle sind schon lange nicht mehr in!","og_description":"Viele glauben immer noch, dass Arbeitshosen aus Baumwolle hergestellt werden und blau sein m\u00fcssen. Die Funktionalit\u00e4t und \u00c4sthetik der Mischmateriallien ist jedoch \u00fcberraschend.","og_url":"https:\/\/lindstromgroup.com\/at\/article\/arbeitshosen-baumwolle-oder-mischmateriallien\/","og_site_name":"Lindstr\u00f6m Austria","article_published_time":"2023-06-14T14:10:44+00:00","article_modified_time":"2025-05-30T10:48:43+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/lindstrom-sites.s3.eu-north-1.amazonaws.com\/wp-content\/uploads\/sites\/26\/2024\/05\/lindstrom-arbeitshosen-baumwolle-oder-mischmateriallien-052024-1.jpg","type":"image\/jpeg"}],"author":"Lindstr\u00f6m Group","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Lindstr\u00f6m Group","Gesch\u00e4tzte Lesezeit":"10 Minuten","Written by":"Lindstr\u00f6m Group"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lindstromgroup.com\/at\/article\/arbeitshosen-baumwolle-oder-mischmateriallien\/#article","isPartOf":{"@id":"https:\/\/lindstromgroup.com\/at\/article\/arbeitshosen-baumwolle-oder-mischmateriallien\/"},"author":{"name":"Lindstr\u00f6m Group","@id":"https:\/\/lindstromgroup.com\/at\/#\/schema\/person\/9111900e3f15be99cf4a104112bf0bc3"},"headline":"Arbeitshosen aus Baumwolle sind schon lange nicht mehr in!","datePublished":"2023-06-14T14:10:44+00:00","dateModified":"2025-05-30T10:48:43+00:00","mainEntityOfPage":{"@id":"https:\/\/lindstromgroup.com\/at\/article\/arbeitshosen-baumwolle-oder-mischmateriallien\/"},"wordCount":1356,"publisher":{"@id":"https:\/\/lindstromgroup.com\/at\/#organization"},"image":{"@id":"https:\/\/lindstromgroup.com\/at\/article\/arbeitshosen-baumwolle-oder-mischmateriallien\/#primaryimage"},"thumbnailUrl":"https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/26\/2024\/05\/lindstrom-arbeitshosen-baumwolle-oder-mischmateriallien-052024-1.jpg","keywords":["#arbeitskleidung","#qualit\u00e4tsmanagement","#sicherheit"],"articleSection":["Blog"],"inLanguage":"de-AT"},{"@type":"WebPage","@id":"https:\/\/lindstromgroup.com\/at\/article\/arbeitshosen-baumwolle-oder-mischmateriallien\/","url":"https:\/\/lindstromgroup.com\/at\/article\/arbeitshosen-baumwolle-oder-mischmateriallien\/","name":"Arbeitshosen aus Baumwolle sind nicht mehr in! - Lindstr\u00f6m","isPartOf":{"@id":"https:\/\/lindstromgroup.com\/at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lindstromgroup.com\/at\/article\/arbeitshosen-baumwolle-oder-mischmateriallien\/#primaryimage"},"image":{"@id":"https:\/\/lindstromgroup.com\/at\/article\/arbeitshosen-baumwolle-oder-mischmateriallien\/#primaryimage"},"thumbnailUrl":"https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/26\/2024\/05\/lindstrom-arbeitshosen-baumwolle-oder-mischmateriallien-052024-1.jpg","datePublished":"2023-06-14T14:10:44+00:00","dateModified":"2025-05-30T10:48:43+00:00","description":"Viele glauben immer noch, dass Arbeitshosen aus Baumwolle hergestellt werden und blau sein m\u00fcssen. Die Funktionalit\u00e4t und \u00c4sthetik der Mischmateriallien ist jedoch \u00fcberraschend.","breadcrumb":{"@id":"https:\/\/lindstromgroup.com\/at\/article\/arbeitshosen-baumwolle-oder-mischmateriallien\/#breadcrumb"},"inLanguage":"de-AT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lindstromgroup.com\/at\/article\/arbeitshosen-baumwolle-oder-mischmateriallien\/"]}]},{"@type":"ImageObject","inLanguage":"de-AT","@id":"https:\/\/lindstromgroup.com\/at\/article\/arbeitshosen-baumwolle-oder-mischmateriallien\/#primaryimage","url":"https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/26\/2024\/05\/lindstrom-arbeitshosen-baumwolle-oder-mischmateriallien-052024-1.jpg","contentUrl":"https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/26\/2024\/05\/lindstrom-arbeitshosen-baumwolle-oder-mischmateriallien-052024-1.jpg","width":1024,"height":682},{"@type":"BreadcrumbList","@id":"https:\/\/lindstromgroup.com\/at\/article\/arbeitshosen-baumwolle-oder-mischmateriallien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lindstromgroup.com\/at\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/lindstromgroup.com\/at\/category\/article\/"},{"@type":"ListItem","position":3,"name":"Arbeitshosen aus Baumwolle sind schon lange nicht mehr in!"}]},{"@type":"WebSite","@id":"https:\/\/lindstromgroup.com\/at\/#website","url":"https:\/\/lindstromgroup.com\/at\/","name":"Lindstr\u00f6m Austria","description":"","publisher":{"@id":"https:\/\/lindstromgroup.com\/at\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lindstromgroup.com\/at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-AT"},{"@type":"Organization","@id":"https:\/\/lindstromgroup.com\/at\/#organization","name":"Lindstr\u00f6m Austria","url":"https:\/\/lindstromgroup.com\/at\/","logo":{"@type":"ImageObject","inLanguage":"de-AT","@id":"https:\/\/lindstromgroup.com\/at\/#\/schema\/logo\/image\/","url":"https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/26\/2023\/10\/Logo512.png","contentUrl":"https:\/\/d2ris6qfzcz0wn.cloudfront.net\/wp-content\/uploads\/sites\/26\/2023\/10\/Logo512.png","width":512,"height":109,"caption":"Lindstr\u00f6m Austria"},"image":{"@id":"https:\/\/lindstromgroup.com\/at\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/lindstromgroup.com\/at\/#\/schema\/person\/9111900e3f15be99cf4a104112bf0bc3","name":"Lindstr\u00f6m Group","image":{"@type":"ImageObject","inLanguage":"de-AT","@id":"https:\/\/secure.gravatar.com\/avatar\/db72e9a46e0f7c5c437401114209c070c0ed0871f3f73ed82792b5cf14c95b5c?s=96&d=mm&r=g93dbf206f3a4403aba72a0da0a795367","url":"https:\/\/secure.gravatar.com\/avatar\/db72e9a46e0f7c5c437401114209c070c0ed0871f3f73ed82792b5cf14c95b5c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/db72e9a46e0f7c5c437401114209c070c0ed0871f3f73ed82792b5cf14c95b5c?s=96&d=mm&r=g","caption":"Lindstr\u00f6m Group"}}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Lindstr\u00f6m Austria","distributor_original_site_url":"https:\/\/lindstromgroup.com\/at","push-errors":false,"_links":{"self":[{"href":"https:\/\/lindstromgroup.com\/at\/wp-json\/wp\/v2\/posts\/16957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lindstromgroup.com\/at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lindstromgroup.com\/at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lindstromgroup.com\/at\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/lindstromgroup.com\/at\/wp-json\/wp\/v2\/comments?post=16957"}],"version-history":[{"count":0,"href":"https:\/\/lindstromgroup.com\/at\/wp-json\/wp\/v2\/posts\/16957\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lindstromgroup.com\/at\/wp-json\/wp\/v2\/media\/16958"}],"wp:attachment":[{"href":"https:\/\/lindstromgroup.com\/at\/wp-json\/wp\/v2\/media?parent=16957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lindstromgroup.com\/at\/wp-json\/wp\/v2\/categories?post=16957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lindstromgroup.com\/at\/wp-json\/wp\/v2\/tags?post=16957"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/lindstromgroup.com\/at\/wp-json\/wp\/v2\/coauthors?post=16957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}